{"id":67695,"date":"2025-03-20T09:07:05","date_gmt":"2025-03-20T07:07:05","guid":{"rendered":"http:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM.jpeg"},"modified":"2025-03-20T09:07:05","modified_gmt":"2025-03-20T07:07:05","slug":"whatsapp-image-2025-03-19-at-5-14-07-pm","status":"inherit","type":"attachment","link":"https:\/\/www.svu.edu.eg\/ar\/%d8%a8%d8%b1%d9%88%d8%aa%d9%88%d9%83%d9%88%d9%84-%d8%aa%d8%b9%d8%a7%d9%88%d9%86-%d8%a8%d9%8a%d9%86-%d8%ac%d8%a7%d9%85%d8%b9%d8%a9-%d8%ac%d9%86%d9%88%d8%a8-%d8%a7%d9%84%d9%88%d8%a7%d8%af%d9%89-%d9%88-6\/whatsapp-image-2025-03-19-at-5-14-07-pm\/","title":{"rendered":"WhatsApp Image 2025-03-19 at 5.14.07 PM"},"author":5,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"class_list":["post-67695","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-300x200.jpeg 300w, https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-1024x682.jpeg 1024w, https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-768x512.jpeg 768w, https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-1536x1023.jpeg 1536w, https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-272x182.jpeg 272w, https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1066,"file":"2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM.jpeg","filesize":396314,"sizes":{"medium":{"file":"WhatsApp-Image-2025-03-19-at-5.14.07-PM-300x200.jpeg","width":300,"height":200,"filesize":17990,"mime_type":"image\/jpeg","source_url":"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-300x200.jpeg"},"large":{"file":"WhatsApp-Image-2025-03-19-at-5.14.07-PM-1024x682.jpeg","width":1024,"height":682,"filesize":124737,"mime_type":"image\/jpeg","source_url":"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-1024x682.jpeg"},"thumbnail":{"file":"WhatsApp-Image-2025-03-19-at-5.14.07-PM-150x150.jpeg","width":150,"height":150,"filesize":8028,"mime_type":"image\/jpeg","source_url":"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-150x150.jpeg"},"medium_large":{"file":"WhatsApp-Image-2025-03-19-at-5.14.07-PM-768x512.jpeg","width":768,"height":512,"filesize":79713,"mime_type":"image\/jpeg","source_url":"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-768x512.jpeg"},"1536x1536":{"file":"WhatsApp-Image-2025-03-19-at-5.14.07-PM-1536x1023.jpeg","width":1536,"height":1023,"filesize":227831,"mime_type":"image\/jpeg","source_url":"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-1536x1023.jpeg"},"sow-carousel-default":{"file":"WhatsApp-Image-2025-03-19-at-5.14.07-PM-272x182.jpeg","width":272,"height":182,"filesize":15287,"mime_type":"image\/jpeg","source_url":"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM-272x182.jpeg"},"full":{"file":"WhatsApp-Image-2025-03-19-at-5.14.07-PM.jpeg","width":1600,"height":1066,"mime_type":"image\/jpeg","source_url":"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":67682,"source_url":"https:\/\/www.svu.edu.eg\/ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.14.07-PM.jpeg","filename":"WhatsApp-Image-2025-03-19-at-5.14.07-PM.jpeg","filesize":396314,"_links":{"self":[{"href":"https:\/\/www.svu.edu.eg\/ar\/wp-json\/wp\/v2\/media\/67695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.svu.edu.eg\/ar\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.svu.edu.eg\/ar\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.svu.edu.eg\/ar\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.svu.edu.eg\/ar\/wp-json\/wp\/v2\/comments?post=67695"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":67682,"href":"https:\/\/www.svu.edu.eg\/ar\/wp-json\/wp\/v2\/posts\/67682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}